{"id":110,"date":"2018-03-19T11:19:45","date_gmt":"2018-03-19T10:19:45","guid":{"rendered":"http:\/\/localhost\/wp-clients\/_rundum\/solid\/?page_id=110"},"modified":"2018-10-23T14:12:57","modified_gmt":"2018-10-23T12:12:57","slug":"referenzen","status":"publish","type":"page","link":"https:\/\/themes.rundum.digital\/solid\/referenzen\/","title":{"rendered":"Referenzen"},"content":{"rendered":"<p>In enim justo, rhoncus ut, imperdiet a, venenatis vitae, justo. Nullam dictum felis eu pede mollis pretium. Integer tincidunt. Cras dapibus. Vivamus elementum semper nisi. Aenean vulputate eleifend tellus. Aenean leo ligula, porttitor eu, consequat vitae, eleifend ac, enim. Aliquam lorem ante, dapibus in, viverra quis, feugiat a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Referenzen<\/p>\n","protected":false},"author":2,"featured_media":66,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"referenzen-no-sidebar.php","meta":{"footnotes":""},"class_list":["post-110","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/pages\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":3,"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/pages\/110\/revisions"}],"predecessor-version":[{"id":232,"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/pages\/110\/revisions\/232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/themes.rundum.digital\/solid\/wp-json\/wp\/v2\/media?parent=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}